{"id":6593,"date":"2021-07-23T16:31:44","date_gmt":"2021-07-23T16:31:44","guid":{"rendered":"https:\/\/luxmanlight.com\/?page_id=6593"},"modified":"2026-02-08T01:45:57","modified_gmt":"2026-02-08T01:45:57","slug":"%d8%a5%d8%b4%d8%a7%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%85%d8%b1%d9%88%d8%b1-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-3","status":"publish","type":"page","link":"https:\/\/luxmanlight.com\/ar\/solar-traffic-lights-3\/","title":{"rendered":"\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6593\" class=\"elementor elementor-6593\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4240c75 e-flex e-con-boxed e-con e-parent\" data-id=\"4240c75\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-005c256 elementor-widget elementor-widget-heading\" data-id=\"005c256\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e36c1db elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e36c1db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9500b23 e-flex e-con-boxed e-con e-parent\" data-id=\"9500b23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-314ea7e e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"314ea7e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2971f92 elementor-widget elementor-widget-spacer\" data-id=\"2971f92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2620b7 elementor-hidden-tablet elementor-hidden-mobile elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"b2620b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i aria-hidden=\\&quot;true\\&quot; class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"\u0642\u0627\u0626\u0645\u0629 \u0637\u0639\u0627\u0645\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-b2620b7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-19141\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%aa%d9%8a-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9\/\" class=\"elementor-item menu-link\">\u0633\u0644\u0633\u0644\u062a\u064a \u0645\u0646 \u0645\u0635\u0627\u0628\u064a\u062d \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-19142\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-mp-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9\/\" class=\"elementor-item menu-link\">\u0633\u0644\u0633\u0644\u0629 MP \u0625\u0646\u0627\u0631\u0629 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3043\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-s3-%d9%85%d9%86-%d9%85%d8%b5%d8%a7%d8%a8%d9%8a%d8%ad-%d8%a7%d9%84%d8%b4%d9%88%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3-2\/\" class=\"elementor-item menu-link\">\u0627\u0644\u0643\u0644 \u0641\u064a \u0648\u0627\u062d\u062f \u0623\u0636\u0648\u0627\u0621 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-19143\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%a7%d9%84%d8%a8%d9%86%d8%af-%d8%a7%d9%84%d9%85%d9%86%d8%aa%d8%ac-2\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-hs-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-2\/\" class=\"elementor-item menu-link\">\u0633\u0644\u0633\u0644\u0629 HS \u0625\u0646\u0627\u0631\u0629 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3348\"><a href=\"https:\/\/luxmanlight.com\/ar\/g2-%d9%86%d9%88%d8%b9-%d8%b3%d8%a8%d9%84%d9%8a%d8%aa-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-2\/\" class=\"elementor-item menu-link\">G2 \u0646\u0648\u0639 \u0633\u0628\u0644\u064a\u062a \u0636\u0648\u0621 \u0627\u0644\u0634\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1447\"><a href=\"https:\/\/luxmanlight.com\/ar\/s3-%d8%a7%d9%84%d8%af%d9%88%d8%a7%d8%a6%d8%b1-%d8%a7%d9%84%d8%aa%d9%84%d9%81%d8%b2%d9%8a%d9%88%d9%86%d9%8a%d8%a9-%d8%a7%d9%84%d9%85%d8%ba%d9%84%d9%82%d8%a9-%d9%84%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7\/\" class=\"elementor-item menu-link\">\u0636\u0648\u0621 \u0627\u0644\u0623\u0645\u0627\u0646 \u0627\u0644\u0634\u0645\u0633\u064a \u0645\u0646 \u0633\u0644\u0633\u0644\u0629 S3C<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1444\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-s2\/\" class=\"elementor-item menu-link\">\u0645\u0635\u0627\u0628\u064a\u062d \u062a\u0639\u0645\u0644 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0645\u0646 \u0633\u0644\u0633\u0644\u0629 S2<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3044\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-ss-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9\/\" class=\"elementor-item menu-link\">\u0633\u0644\u0633\u0644\u0629 SS \u0625\u0646\u0627\u0631\u0629 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1446\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-%d8%b3%d8%a7%d8%af%d8%b3\/\" class=\"elementor-item menu-link\">\u0623\u0636\u0648\u0627\u0621 \u0634\u0645\u0633\u064a\u0629 \u0645\u0646\u0641\u0635\u0644\u0629 \u0645\u0646 \u0633\u0644\u0633\u0644\u0629 SF<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-6600\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%a5%d8%b4%d8%a7%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%85%d8%b1%d9%88%d8%b1-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-3\/\" class=\"elementor-item menu-link\">\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-18107\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/%d8%a8%d8%b1%d8%ac-%d8%a7%d9%84%d8%a5%d8%b6%d8%a7%d8%a1%d8%a9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-%d8%a7%d9%84%d9%85%d8%ad%d9%85%d9%88%d9%84\/\" class=\"elementor-item menu-link\">\u0628\u0631\u062c \u0627\u0644\u0625\u0636\u0627\u0621\u0629 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0627\u0644\u0645\u062a\u0646\u0642\u0644\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71664\"><a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-wind-hybrid-street-light\/\" class=\"elementor-item menu-link\">\u0636\u0648\u0621 \u0627\u0644\u0634\u0627\u0631\u0639 \u0627\u0644\u0647\u062c\u064a\u0646 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71665\"><a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/eagle-gen4-led-street-light\/\" class=\"elementor-item menu-link\">\u0645\u0635\u0628\u0627\u062d \u0634\u0627\u0631\u0639 LED<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71666\"><a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-flood-light\/\" class=\"elementor-item menu-link\">\u0636\u0648\u0621 \u0627\u0644\u0641\u064a\u0636\u0627\u0646\u0627\u062a \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71706\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/solar-accessories\/\" class=\"elementor-item menu-link\">\u0645\u0644\u062d\u0642\u0627\u062a \u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71707\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/new-product\/\" class=\"elementor-item menu-link\">\u0645\u0646\u062a\u062c \u062c\u062f\u064a\u062f<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"\u062a\u0628\u062f\u064a\u0644 \u0627\u0644\u0642\u0627\u0626\u0645\u0629\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-b2620b7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-19141\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%aa%d9%8a-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0633\u0644\u0633\u0644\u062a\u064a \u0645\u0646 \u0645\u0635\u0627\u0628\u064a\u062d \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-19142\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-mp-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0633\u0644\u0633\u0644\u0629 MP \u0625\u0646\u0627\u0631\u0629 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3043\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-s3-%d9%85%d9%86-%d9%85%d8%b5%d8%a7%d8%a8%d9%8a%d8%ad-%d8%a7%d9%84%d8%b4%d9%88%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3-2\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0627\u0644\u0643\u0644 \u0641\u064a \u0648\u0627\u062d\u062f \u0623\u0636\u0648\u0627\u0621 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-19143\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%a7%d9%84%d8%a8%d9%86%d8%af-%d8%a7%d9%84%d9%85%d9%86%d8%aa%d8%ac-2\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-hs-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-2\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0633\u0644\u0633\u0644\u0629 HS \u0625\u0646\u0627\u0631\u0629 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3348\"><a href=\"https:\/\/luxmanlight.com\/ar\/g2-%d9%86%d9%88%d8%b9-%d8%b3%d8%a8%d9%84%d9%8a%d8%aa-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-2\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">G2 \u0646\u0648\u0639 \u0633\u0628\u0644\u064a\u062a \u0636\u0648\u0621 \u0627\u0644\u0634\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1447\"><a href=\"https:\/\/luxmanlight.com\/ar\/s3-%d8%a7%d9%84%d8%af%d9%88%d8%a7%d8%a6%d8%b1-%d8%a7%d9%84%d8%aa%d9%84%d9%81%d8%b2%d9%8a%d9%88%d9%86%d9%8a%d8%a9-%d8%a7%d9%84%d9%85%d8%ba%d9%84%d9%82%d8%a9-%d9%84%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0636\u0648\u0621 \u0627\u0644\u0623\u0645\u0627\u0646 \u0627\u0644\u0634\u0645\u0633\u064a \u0645\u0646 \u0633\u0644\u0633\u0644\u0629 S3C<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1444\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-s2\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0645\u0635\u0627\u0628\u064a\u062d \u062a\u0639\u0645\u0644 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0645\u0646 \u0633\u0644\u0633\u0644\u0629 S2<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3044\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-ss-%d8%b6%d9%88%d8%a1-%d8%a7%d9%84%d8%b4%d8%a7%d8%b1%d8%b9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0633\u0644\u0633\u0644\u0629 SS \u0625\u0646\u0627\u0631\u0629 \u0627\u0644\u0634\u0648\u0627\u0631\u0639 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1446\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/%d8%b3%d9%84%d8%b3%d9%84%d8%a9-%d8%b3%d8%a7%d8%af%d8%b3\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0623\u0636\u0648\u0627\u0621 \u0634\u0645\u0633\u064a\u0629 \u0645\u0646\u0641\u0635\u0644\u0629 \u0645\u0646 \u0633\u0644\u0633\u0644\u0629 SF<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-6600\"><a href=\"https:\/\/luxmanlight.com\/ar\/%d8%a5%d8%b4%d8%a7%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%85%d8%b1%d9%88%d8%b1-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-3\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-18107\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/%d8%a8%d8%b1%d8%ac-%d8%a7%d9%84%d8%a5%d8%b6%d8%a7%d8%a1%d8%a9-%d8%a8%d8%a7%d9%84%d8%b7%d8%a7%d9%82%d8%a9-%d8%a7%d9%84%d8%b4%d9%85%d8%b3%d9%8a%d8%a9-%d8%a7%d9%84%d9%85%d8%ad%d9%85%d9%88%d9%84\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0628\u0631\u062c \u0627\u0644\u0625\u0636\u0627\u0621\u0629 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0627\u0644\u0645\u062a\u0646\u0642\u0644\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71664\"><a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-wind-hybrid-street-light\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0636\u0648\u0621 \u0627\u0644\u0634\u0627\u0631\u0639 \u0627\u0644\u0647\u062c\u064a\u0646 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71665\"><a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/eagle-gen4-led-street-light\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0645\u0635\u0628\u0627\u062d \u0634\u0627\u0631\u0639 LED<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71666\"><a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-flood-light\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0636\u0648\u0621 \u0627\u0644\u0641\u064a\u0636\u0627\u0646\u0627\u062a \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71706\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/solar-accessories\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0645\u0644\u062d\u0642\u0627\u062a \u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-71707\"><a href=\"https:\/\/luxmanlight.com\/ar\/product_entries\/new-product\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u0645\u0646\u062a\u062c \u062c\u062f\u064a\u062f<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae1caa3 e-con-full e-flex e-con e-child\" data-id=\"ae1caa3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b80b9d elementor-widget elementor-widget-spacer\" data-id=\"0b80b9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e3a906 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"2e3a906\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-71424 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-traffic-sign-luxman-solar-lighting-manufacturer\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-768x768.png\" class=\"attachment-medium_large size-medium_large wp-image-6703\" alt=\"\u0625\u0634\u0627\u0631\u0629 \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\" srcset=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-768x768.png 768w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-300x300.png 300w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-1030x1030.png 1030w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-80x80.png 80w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-36x36.png 36w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-180x180.png 180w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-705x705.png 705w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-120x120.png 120w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign-450x450.png 450w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-sign.png 1246w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-traffic-sign-luxman-solar-lighting-manufacturer\/\" >\n\t\t\t\t\u0625\u0634\u0627\u0631\u0629 \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-71435 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-traffic-yellow-flashing-lights\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"495\" height=\"400\" src=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffice-safety-warning-yellow-lights.png\" class=\"attachment-medium_large size-medium_large wp-image-6684\" alt=\"\u0623\u0636\u0648\u0627\u0621 \u0635\u0641\u0631\u0627\u0621 \u062a\u062d\u0630\u064a\u0631\u064a\u0629 \u0644\u0644\u0633\u0644\u0627\u0645\u0629 \u0627\u0644\u0645\u0631\u0648\u0631\u064a\u0629 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\" srcset=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffice-safety-warning-yellow-lights.png 495w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffice-safety-warning-yellow-lights-300x242.png 300w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffice-safety-warning-yellow-lights-450x364.png 450w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-traffic-yellow-flashing-lights\/\" >\n\t\t\t\t\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0627\u0644\u0635\u0641\u0631\u0627\u0621 \u0627\u0644\u0648\u0627\u0645\u0636\u0629\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-71447 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-warning-traffic-light-luxman-solar-lighting\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"768\" height=\"752\" src=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-warning-lighting-768x752.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6623\" alt=\"\u0625\u0636\u0627\u0621\u0629 \u062a\u062d\u0630\u064a\u0631 \u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0648\u0631 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\" srcset=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-warning-lighting-768x752.jpg 768w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-warning-lighting-300x294.jpg 300w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-warning-lighting-36x36.jpg 36w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-warning-lighting-705x690.jpg 705w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-warning-lighting-450x441.jpg 450w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/08\/solar-traffic-warning-lighting.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-warning-traffic-light-luxman-solar-lighting\/\" >\n\t\t\t\t\u0625\u0634\u0627\u0631\u0629 \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u062a\u062d\u0630\u064a\u0631\u064a\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-71462 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/luxmanlight.com\/ar\/product-item\/cat-eye-solar-road-stud-luxman-solar-lighting-manufacturer\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-768x768.png\" class=\"attachment-medium_large size-medium_large wp-image-6591\" alt=\"\u062a\u0631\u0635\u064a\u0639 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0639\u064a\u0646 \u0627\u0644\u0642\u0637\" srcset=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-768x768.png 768w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-300x300.png 300w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-1030x1030.png 1030w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-80x80.png 80w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-36x36.png 36w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-180x180.png 180w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-705x705.png 705w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-120x120.png 120w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs-450x450.png 450w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/cat-eye-solar-road-studs.png 1246w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/cat-eye-solar-road-stud-luxman-solar-lighting-manufacturer\/\" >\n\t\t\t\t\u0645\u0633\u0645\u0627\u0631 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0634\u0645\u0633\u064a\u0629 \u0639\u064a\u0646 \u0627\u0644\u0642\u0637\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-71483 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-powered-road-studs-cats-eyes-solar-street-light-manufacturer\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"620\" src=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light-768x620.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6578\" alt=\"\u062a\u0631\u0635\u064a\u0639 \u0627\u0644\u0637\u0631\u064a\u0642 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\" srcset=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light-768x620.jpg 768w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light-300x242.jpg 300w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light-1030x832.jpg 1030w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light-495x400.jpg 495w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light-705x569.jpg 705w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light-450x363.jpg 450w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/Solar-Powered-Road-Studs-light.jpg 1246w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-powered-road-studs-cats-eyes-solar-street-light-manufacturer\/\" >\n\t\t\t\t\u0645\u0633\u0627\u0645\u064a\u0631 \u0627\u0644\u0637\u0631\u0642 \u0648\u0639\u064a\u0648\u0646 \u0627\u0644\u0642\u0637\u0637 \u0627\u0644\u062a\u064a \u062a\u0639\u0645\u0644 \u0628\u0627\u0644\u0637\u0627\u0642\u0629 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-71493 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-road-stud\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-768x768.png\" class=\"attachment-medium_large size-medium_large wp-image-6533\" alt=\"\u062a\u0631\u0635\u064a\u0639 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0634\u0645\u0633\u064a\u0629\" srcset=\"https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-768x768.png 768w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-300x300.png 300w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-1030x1030.png 1030w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-80x80.png 80w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-36x36.png 36w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-180x180.png 180w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-705x705.png 705w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-120x120.png 120w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6-450x450.png 450w, https:\/\/luxmanlight.com\/wp-content\/uploads\/2021\/07\/solar-road-studs-6.png 1246w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/luxmanlight.com\/ar\/product-item\/solar-road-stud\/\" >\n\t\t\t\t\u0645\u0632\u0631\u0639\u0629 \u0633\u0648\u0644\u0627\u0631 \u0631\u0648\u062f \u0633\u062a\u062f\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40816e0 elementor-widget elementor-widget-spacer\" data-id=\"40816e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17807d2 e-flex e-con-boxed e-con e-parent\" data-id=\"17807d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1a5434 elementor-widget elementor-widget-heading\" data-id=\"f1a5434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0646\u062d\u0646 \u0646\u062a\u0637\u0644\u0639 \u0625\u0644\u0649 \u0625\u062c\u0631\u0627\u0621 \u062d\u0648\u0627\u0631 \u062a\u062c\u0627\u0631\u064a \u0645\u062b\u064a\u0631 \u0644\u0644\u0627\u0647\u062a\u0645\u0627\u0645 \u0645\u0639\u0643!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cff1c40 elementor-widget elementor-widget-text-editor\" data-id=\"cff1c40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1997-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1997\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/6593#wpcf7-f1997-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0646\u0645\u0648\u0630\u062c \u0627\u0644\u0627\u062a\u0635\u0627\u0644\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/ar\/wp-json\/wp\/v2\/pages\/6593#wpcf7-f1997-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1997\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1997-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"onecolumn\">\n\t<div class=\"input_item\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u0627\u0633\u0645*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"input_item\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u0628\u0631\u064a\u062f \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"input_item\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-telephone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u0647\u0627\u062a\u0641*\" value=\"\" type=\"tel\" name=\"your-telephone\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"input_item\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"\u0631\u0633\u0627\u0644\u0629*\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"\u064a\u064f\u0642\u062f\u0651\u0650\u0645\" \/>\n<\/p>\n<p><script>\ndocument.addEventListener( 'wpcf7mailsent', function( event ) {\n location = '\/thank-you\/';\n}, false );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0645\u0631\u0648\u0631 \u0627\u0644\u0634\u0645\u0633\u064a\u0629. \u0646\u062a\u0637\u0644\u0639 \u0625\u0644\u0649 \u062d\u0648\u0627\u0631 \u062a\u062c\u0627\u0631\u064a \u0645\u062b\u0645\u0631 \u0645\u0639\u0643\u0645!<\/p>","protected":false},"author":8,"featured_media":6684,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6593","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/pages\/6593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/comments?post=6593"}],"version-history":[{"count":22,"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/pages\/6593\/revisions"}],"predecessor-version":[{"id":71497,"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/pages\/6593\/revisions\/71497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/media\/6684"}],"wp:attachment":[{"href":"https:\/\/luxmanlight.com\/ar\/wp-json\/wp\/v2\/media?parent=6593"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}